{"id":92579,"date":"2026-08-27T09:57:49","date_gmt":"2026-08-27T07:57:49","guid":{"rendered":"https:\/\/cardinal-tapes.com\/klebebaender\/senza-categoria\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\/"},"modified":"2026-08-27T09:57:49","modified_gmt":"2026-08-27T07:57:49","slug":"duplocoll-810-nastro-adesivo-in-carta-non-tessuta","status":"publish","type":"product","link":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\/","title":{"rendered":"DuploCOLL\u00ae 810 Nastro adesivo in carta non tessuta"},"content":{"rendered":"<p><strong>Lohmann <\/strong><strong style=\"font-size: inherit;\">DuploCOLL\u00ae 810<\/strong><span style=\"font-size: inherit;\">  \u00c8 un nastro biadesivo a basse emissioni ed ecologico, dotato di un supporto in carta speciale e di un adesivo acrilico a dispersione ad alte prestazioni. Si contraddistingue per un\u2019eccellente adesione iniziale e un\u2019elevata coesione, garantendo un\u2019adesione affidabile su una vasta gamma di materiali. <\/span><\/p>\n<div>\n<p>Il nastro adesivo \u00e8 particolarmente indicato per applicazioni negli interni delle automobili, ad esempio per il fissaggio di strisce di moquette sui battitacchi in plastica. Inoltre, \u00e8 ideale per il rivestimento autoadesivo di materiali quali plastica, metallo, schiuma, tessuto e stoffa. Grazie alla sua buona resistenza all\u2019invecchiamento e ai raggi UV, nonch\u00e9 alla sua idoneit\u00e0 per superfici a pori grossolani, DuploCOLL\u00ae 810 rappresenta una soluzione versatile per incollaggi di lunga durata.  <\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Lohmann DuploCOLL\u00ae 810 \u00c8 un nastro biadesivo a basse emissioni ed ecologico, dotato di un supporto in carta speciale e di un adesivo acrilico a dispersione ad alte prestazioni. Si contraddistingue per un\u2019eccellente adesione iniziale e un\u2019elevata coesione, garantendo un\u2019adesione affidabile su una vasta gamma di materiali. Il nastro adesivo \u00e8 particolarmente indicato per applicazioni &#8230; <a title=\"DuploCOLL\u00ae 810 Nastro adesivo in carta non tessuta\" class=\"read-more\" href=\"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\/\" aria-label=\"Per saperne di pi\u00f9 su DuploCOLL\u00ae 810 Nastro adesivo in carta non tessuta\">Leggi tutto<\/a><\/p>\n","protected":false},"featured_media":91508,"template":"","meta":{"_acf_changed":false},"pwb-brand":[7835],"product_brand":[],"product_cat":[1824],"product_tag":[],"class_list":["post-92579","product","type-product","status-publish","has-post-thumbnail","pwb-brand-lohmann-it","product_cat-nastri-biadesivi","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lohmann DuploCOLL\u00ae 810 carta non tessuta | Cardinal TAPES<\/title>\n<meta name=\"description\" content=\"Lohmann DuploCOLL\u00ae 810 \u00e8 un nastro biadesivo a basse emissioni ed ecologico, dotato di un potente adesivo acrilico a dispersione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lohmann DuploCOLL\u00ae 810 carta non tessuta | Cardinal TAPES\" \/>\n<meta property=\"og:description\" content=\"Lohmann DuploCOLL\u00ae 810 \u00e8 un nastro biadesivo a basse emissioni ed ecologico, dotato di un potente adesivo acrilico a dispersione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\/\" \/>\n<meta property=\"og:site_name\" content=\"cardinal Tapes\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/PROD_DuploCOLL810_DuploCOLL265_DuploCOLL_gelb-mit-weiss.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\\\/\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\\\/\",\"name\":\"Lohmann DuploCOLL\u00ae 810 carta non tessuta | Cardinal TAPES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/PROD_DuploCOLL810_DuploCOLL265_DuploCOLL_gelb-mit-weiss.jpg\",\"datePublished\":\"2026-08-27T07:57:49+00:00\",\"description\":\"Lohmann DuploCOLL\u00ae 810 \u00e8 un nastro biadesivo a basse emissioni ed ecologico, dotato di un potente adesivo acrilico a dispersione.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/PROD_DuploCOLL810_DuploCOLL265_DuploCOLL_gelb-mit-weiss.jpg\",\"contentUrl\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/PROD_DuploCOLL810_DuploCOLL265_DuploCOLL_gelb-mit-weiss.jpg\",\"width\":1920,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i prodotti\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DuploCOLL\u00ae 810 Nastro adesivo in carta non tessuta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/\",\"name\":\"cardinal TAPES\",\"description\":\"Klebetechnik aus Wuppertal\",\"publisher\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/#organization\",\"name\":\"Cardinal Tapes\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/cardinal-tapes-logo.svg\",\"contentUrl\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/cardinal-tapes-logo.svg\",\"width\":216,\"height\":56,\"caption\":\"Cardinal Tapes\"},\"image\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lohmann DuploCOLL\u00ae 810 carta non tessuta | Cardinal TAPES","description":"Lohmann DuploCOLL\u00ae 810 \u00e8 un nastro biadesivo a basse emissioni ed ecologico, dotato di un potente adesivo acrilico a dispersione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\/","og_locale":"it_IT","og_type":"article","og_title":"Lohmann DuploCOLL\u00ae 810 carta non tessuta | Cardinal TAPES","og_description":"Lohmann DuploCOLL\u00ae 810 \u00e8 un nastro biadesivo a basse emissioni ed ecologico, dotato di un potente adesivo acrilico a dispersione.","og_url":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\/","og_site_name":"cardinal Tapes","og_image":[{"width":1920,"height":1920,"url":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/PROD_DuploCOLL810_DuploCOLL265_DuploCOLL_gelb-mit-weiss.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\/","url":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\/","name":"Lohmann DuploCOLL\u00ae 810 carta non tessuta | Cardinal TAPES","isPartOf":{"@id":"https:\/\/cardinal-tapes.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\/#primaryimage"},"image":{"@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\/#primaryimage"},"thumbnailUrl":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/PROD_DuploCOLL810_DuploCOLL265_DuploCOLL_gelb-mit-weiss.jpg","datePublished":"2026-08-27T07:57:49+00:00","description":"Lohmann DuploCOLL\u00ae 810 \u00e8 un nastro biadesivo a basse emissioni ed ecologico, dotato di un potente adesivo acrilico a dispersione.","breadcrumb":{"@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\/#primaryimage","url":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/PROD_DuploCOLL810_DuploCOLL265_DuploCOLL_gelb-mit-weiss.jpg","contentUrl":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/PROD_DuploCOLL810_DuploCOLL265_DuploCOLL_gelb-mit-weiss.jpg","width":1920,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/duplocoll-810-nastro-adesivo-in-carta-non-tessuta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cardinal-tapes.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tutti i prodotti","item":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/"},{"@type":"ListItem","position":3,"name":"DuploCOLL\u00ae 810 Nastro adesivo in carta non tessuta"}]},{"@type":"WebSite","@id":"https:\/\/cardinal-tapes.com\/it\/#website","url":"https:\/\/cardinal-tapes.com\/it\/","name":"cardinal TAPES","description":"Klebetechnik aus Wuppertal","publisher":{"@id":"https:\/\/cardinal-tapes.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cardinal-tapes.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cardinal-tapes.com\/it\/#organization","name":"Cardinal Tapes","url":"https:\/\/cardinal-tapes.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cardinal-tapes.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/cardinal-tapes-logo.svg","contentUrl":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/cardinal-tapes-logo.svg","width":216,"height":56,"caption":"Cardinal Tapes"},"image":{"@id":"https:\/\/cardinal-tapes.com\/it\/#\/schema\/logo\/image\/"}}]}},"brands":[{"id":7835,"name":"Lohmann","slug":"lohmann-it"}],"_links":{"self":[{"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/product\/92579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/media\/91508"}],"wp:attachment":[{"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/media?parent=92579"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/pwb-brand?post=92579"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/product_brand?post=92579"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/product_cat?post=92579"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/product_tag?post=92579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}