{"id":45277,"date":"2018-05-30T16:09:26","date_gmt":"2018-05-30T14:09:26","guid":{"rendered":"https:\/\/cardinal.pixel-tal.de\/klebebaender\/senza-categoria\/3m-vhb-nastro-5952-f\/"},"modified":"2025-07-02T17:13:04","modified_gmt":"2025-07-02T15:13:04","slug":"3m-5952-f-vhb-klebeband","status":"publish","type":"product","link":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/3m-5952-f-vhb-klebeband\/","title":{"rendered":"3M\u2122 VHB\u2122 Nastro 5952 F"},"content":{"rendered":"<p>I nastri 3M\u2122 VHB ad alte prestazioni sono nastri biadesivi realizzati con adesivo acrilico a cellule chiuse. Offrono un&#8217;elevata adattabilit\u00e0 alle superfici da incollare. Le superfici lisce o strutturate possono essere incollate su tutta la superficie senza tensioni. Ideale per molte superfici a basso consumo energetico, superfici verniciate a polvere, plastica (non PVC morbido) o vetro.<\/p>\n<p><strong>Descrizione<\/strong><br \/>\nI sistemi di incollaggio ad alte prestazioni 3M\u2122 VHB\u2122, di colore grigio scuro, offrono un&#8217;ottima adattabilit\u00e0 alle superfici da incollare. Questa caratteristica consente di incollare superfici sottili e strutturate su tutta la superficie senza tensioni. Inoltre, sono caratterizzati da una buona resistenza agli urti a temperature minime e da un&#8217;elevata adesione istantanea.<\/p>\n<p><strong>Applicazioni<\/strong><br \/>\n&#8211; Incollaggio di pannelli a telai<br \/>\n&#8211; Incollaggio di elementi di irrigidimento a pannelli<br \/>\n&#8211; Incollaggio di materiale decorativo, modanature, parti aggiuntive o display elettronici<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I nastri 3M\u2122 VHB ad alte prestazioni sono nastri biadesivi realizzati con adesivo acrilico a cellule chiuse. Offrono un&#8217;elevata adattabilit\u00e0 alle superfici da incollare. Le superfici lisce o strutturate possono essere incollate su tutta la superficie senza tensioni. Ideale per molte superfici a basso consumo energetico, superfici verniciate a polvere, plastica (non PVC morbido) o [&hellip;]<\/p>\n","protected":false},"featured_media":26649,"template":"","meta":{"_acf_changed":false},"pwb-brand":[2166],"product_brand":[],"product_cat":[7587,1824],"product_tag":[],"class_list":["post-45277","product","type-product","status-publish","has-post-thumbnail","pwb-brand-3m-it","product_cat-presentazione-del-contributo","product_cat-nastri-biadesivi","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nastro 3M\u2122 VHB\u2122 5952 F | Cardinal TAPES<\/title>\n<meta name=\"description\" content=\"I nastri adesivi ad alte prestazioni 3M 5952 F VHB sono nastri biadesivi realizzati con adesivo acrilico. Per saperne di pi\u00f9 sul 3M 5952 F VHB, cliccare qui.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/3m-5952-f-vhb-klebeband\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nastro 3M\u2122 VHB\u2122 5952 F | Cardinal TAPES\" \/>\n<meta property=\"og:description\" content=\"I nastri adesivi ad alte prestazioni 3M 5952 F VHB sono nastri biadesivi realizzati con adesivo acrilico. Per saperne di pi\u00f9 sul 3M 5952 F VHB, cliccare qui.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/3m-5952-f-vhb-klebeband\/\" \/>\n<meta property=\"og:site_name\" content=\"cardinal TAPES\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-02T15:13:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/3m-5952-f-vhb-doppelseitiges-klebeband-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1251\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/3m-5952-f-vhb-klebeband\\\/\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/3m-5952-f-vhb-klebeband\\\/\",\"name\":\"Nastro 3M\u2122 VHB\u2122 5952 F | Cardinal TAPES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/3m-5952-f-vhb-klebeband\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/3m-5952-f-vhb-klebeband\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/3m-5952-f-vhb-doppelseitiges-klebeband-scaled.jpg\",\"datePublished\":\"2018-05-30T14:09:26+00:00\",\"dateModified\":\"2025-07-02T15:13:04+00:00\",\"description\":\"I nastri adesivi ad alte prestazioni 3M 5952 F VHB sono nastri biadesivi realizzati con adesivo acrilico. Per saperne di pi\u00f9 sul 3M 5952 F VHB, cliccare qui.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/3m-5952-f-vhb-klebeband\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/3m-5952-f-vhb-klebeband\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/3m-5952-f-vhb-klebeband\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/3m-5952-f-vhb-doppelseitiges-klebeband-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/3m-5952-f-vhb-doppelseitiges-klebeband-scaled.jpg\",\"width\":2560,\"height\":1251,\"caption\":\"3m 5952f vhb nastro biadesivo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/nastri-biadesivi\\\/3m-5952-f-vhb-klebeband\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/casa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nastri adesivi\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi-it\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Doppelseitige Klebeb\u00e4nder\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/kategorie\\\/doppelseitige-klebebaender\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"3M\u2122 VHB\u2122 Nastro 5952 F\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/#website\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/\",\"name\":\"cardinal TAPES\",\"description\":\"Klebetechnik aus Wuppertal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cardinal-tapes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nastro 3M\u2122 VHB\u2122 5952 F | Cardinal TAPES","description":"I nastri adesivi ad alte prestazioni 3M 5952 F VHB sono nastri biadesivi realizzati con adesivo acrilico. Per saperne di pi\u00f9 sul 3M 5952 F VHB, cliccare qui.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/3m-5952-f-vhb-klebeband\/","og_locale":"it_IT","og_type":"article","og_title":"Nastro 3M\u2122 VHB\u2122 5952 F | Cardinal TAPES","og_description":"I nastri adesivi ad alte prestazioni 3M 5952 F VHB sono nastri biadesivi realizzati con adesivo acrilico. Per saperne di pi\u00f9 sul 3M 5952 F VHB, cliccare qui.","og_url":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/3m-5952-f-vhb-klebeband\/","og_site_name":"cardinal TAPES","article_modified_time":"2025-07-02T15:13:04+00:00","og_image":[{"width":2560,"height":1251,"url":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/3m-5952-f-vhb-doppelseitiges-klebeband-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/3m-5952-f-vhb-klebeband\/","url":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/3m-5952-f-vhb-klebeband\/","name":"Nastro 3M\u2122 VHB\u2122 5952 F | Cardinal TAPES","isPartOf":{"@id":"https:\/\/cardinal-tapes.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/3m-5952-f-vhb-klebeband\/#primaryimage"},"image":{"@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/3m-5952-f-vhb-klebeband\/#primaryimage"},"thumbnailUrl":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/3m-5952-f-vhb-doppelseitiges-klebeband-scaled.jpg","datePublished":"2018-05-30T14:09:26+00:00","dateModified":"2025-07-02T15:13:04+00:00","description":"I nastri adesivi ad alte prestazioni 3M 5952 F VHB sono nastri biadesivi realizzati con adesivo acrilico. Per saperne di pi\u00f9 sul 3M 5952 F VHB, cliccare qui.","breadcrumb":{"@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/3m-5952-f-vhb-klebeband\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/3m-5952-f-vhb-klebeband\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/3m-5952-f-vhb-klebeband\/#primaryimage","url":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/3m-5952-f-vhb-doppelseitiges-klebeband-scaled.jpg","contentUrl":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/3m-5952-f-vhb-doppelseitiges-klebeband-scaled.jpg","width":2560,"height":1251,"caption":"3m 5952f vhb nastro biadesivo"},{"@type":"BreadcrumbList","@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/nastri-biadesivi\/3m-5952-f-vhb-klebeband\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cardinal-tapes.com\/it\/casa\/"},{"@type":"ListItem","position":2,"name":"Nastri adesivi","item":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi-it\/"},{"@type":"ListItem","position":3,"name":"Doppelseitige Klebeb\u00e4nder","item":"https:\/\/cardinal-tapes.com\/kategorie\/doppelseitige-klebebaender\/"},{"@type":"ListItem","position":4,"name":"3M\u2122 VHB\u2122 Nastro 5952 F"}]},{"@type":"WebSite","@id":"https:\/\/cardinal-tapes.com\/#website","url":"https:\/\/cardinal-tapes.com\/","name":"cardinal TAPES","description":"Klebetechnik aus Wuppertal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cardinal-tapes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"brands":[{"id":2166,"name":"3M","slug":"3m-it"}],"_links":{"self":[{"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/product\/45277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/media\/26649"}],"wp:attachment":[{"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/media?parent=45277"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/pwb-brand?post=45277"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/product_brand?post=45277"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/product_cat?post=45277"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/product_tag?post=45277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}