{"id":38411,"date":"2023-02-24T13:03:28","date_gmt":"2023-06-05T14:47:05","guid":{"rendered":"https:\/\/cardinal.pixel-tal.de\/klebebaender\/senza-categoria\/orabond-1822-nastro-adesivo-in-schiuma-pe\/"},"modified":"2023-06-05T16:47:05","modified_gmt":"2023-06-05T14:47:05","slug":"orabond-1822-pe-schiuma-nastro-adesivo","status":"publish","type":"product","link":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/aree-di-applicazione\/ingegneria-meccanica\/orabond-1822-pe-schiuma-nastro-adesivo\/","title":{"rendered":"ORABOND\u00ae 1822 Nastro adesivo in schiuma PE"},"content":{"rendered":"<p>Il nastro biadesivo \u00e8 costituito da una schiuma nera di polietilene a cellule chiuse rivestita su entrambi i lati con<br \/>\nrivestito con un adesivo acrilico sensibile alla pressione. L&#8217;adesivo sensibile alla pressione \u00e8 caratterizzato da una buona adesione su superfici critiche.<br \/>\nsuperfici del substrato.<\/p>\n<p><strong>Ambito di applicazione<\/strong><br \/>\nPer l&#8217;incollaggio commerciale permanente e il montaggio di un&#8217;ampia variet\u00e0 di materiali come metallo, plastica, vetro e<br \/>\nCeramica. Incollaggio duraturo di insegne e fasce, scritte e parti in plastica stampata. A causa degli elevati raggi UV,<br \/>\nLa resistenza all&#8217;acqua e all&#8217;invecchiamento rende questo prodotto adatto ad applicazioni esterne. Questo prodotto offre un<br \/>\nincollaggio esterno duraturo anche su pannelli di alluminio e vetro ed \u00e8 quindi adatto alla produzione di pannelli solari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il nastro biadesivo \u00e8 costituito da una schiuma nera di polietilene a cellule chiuse rivestita su entrambi i lati con rivestito con un adesivo acrilico sensibile alla pressione. L&#8217;adesivo sensibile alla pressione \u00e8 caratterizzato da una buona adesione su superfici critiche. superfici del substrato. Ambito di applicazione Per l&#8217;incollaggio commerciale permanente e il montaggio di [&hellip;]<\/p>\n","protected":false},"featured_media":29241,"template":"","meta":{"_acf_changed":false},"pwb-brand":[2802],"product_brand":[],"product_cat":[1731,1824],"product_tag":[],"class_list":["post-38411","product","type-product","status-publish","has-post-thumbnail","pwb-brand-orafol-it","product_cat-ingegneria-meccanica","product_cat-nastri-biadesivi","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ORABOND\u00ae 1822 Nastro adesivo in schiuma PE | Cardinal TAPES<\/title>\n<meta name=\"description\" content=\"Orabond 1822 \u00e8 costituito da una schiuma di polietilene nera a cellule chiuse rivestita su entrambi i lati con un adesivo acrilico sensibile alla pressione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/ingegneria-meccanica\/orabond-1822-pe-schiuma-nastro-adesivo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ORABOND\u00ae 1822 Nastro adesivo in schiuma PE | Cardinal TAPES\" \/>\n<meta property=\"og:description\" content=\"Orabond 1822 \u00e8 costituito da una schiuma di polietilene nera a cellule chiuse rivestita su entrambi i lati con un adesivo acrilico sensibile alla pressione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/ingegneria-meccanica\/orabond-1822-pe-schiuma-nastro-adesivo\/\" \/>\n<meta property=\"og:site_name\" content=\"cardinal TAPES\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/1822W-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/ingegneria-meccanica\\\/orabond-1822-pe-schiuma-nastro-adesivo\\\/\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/ingegneria-meccanica\\\/orabond-1822-pe-schiuma-nastro-adesivo\\\/\",\"name\":\"ORABOND\u00ae 1822 Nastro adesivo in schiuma PE | Cardinal TAPES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/ingegneria-meccanica\\\/orabond-1822-pe-schiuma-nastro-adesivo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/ingegneria-meccanica\\\/orabond-1822-pe-schiuma-nastro-adesivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/1822W-scaled.jpg\",\"datePublished\":\"2023-06-05T14:47:05+00:00\",\"description\":\"Orabond 1822 \u00e8 costituito da una schiuma di polietilene nera a cellule chiuse rivestita su entrambi i lati con un adesivo acrilico sensibile alla pressione.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/ingegneria-meccanica\\\/orabond-1822-pe-schiuma-nastro-adesivo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/ingegneria-meccanica\\\/orabond-1822-pe-schiuma-nastro-adesivo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/ingegneria-meccanica\\\/orabond-1822-pe-schiuma-nastro-adesivo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/1822W-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/1822W-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi\\\/ingegneria-meccanica\\\/orabond-1822-pe-schiuma-nastro-adesivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/casa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nastri adesivi\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/nastri-adesivi-it\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ingegneria meccanica\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/it\\\/categoria\\\/ingegneria-meccanica\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"ORABOND\u00ae 1822 Nastro adesivo in schiuma PE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/#website\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/\",\"name\":\"cardinal TAPES\",\"description\":\"Klebetechnik aus Wuppertal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cardinal-tapes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ORABOND\u00ae 1822 Nastro adesivo in schiuma PE | Cardinal TAPES","description":"Orabond 1822 \u00e8 costituito da una schiuma di polietilene nera a cellule chiuse rivestita su entrambi i lati con un adesivo acrilico sensibile alla pressione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/ingegneria-meccanica\/orabond-1822-pe-schiuma-nastro-adesivo\/","og_locale":"it_IT","og_type":"article","og_title":"ORABOND\u00ae 1822 Nastro adesivo in schiuma PE | Cardinal TAPES","og_description":"Orabond 1822 \u00e8 costituito da una schiuma di polietilene nera a cellule chiuse rivestita su entrambi i lati con un adesivo acrilico sensibile alla pressione.","og_url":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/ingegneria-meccanica\/orabond-1822-pe-schiuma-nastro-adesivo\/","og_site_name":"cardinal TAPES","og_image":[{"width":2560,"height":1707,"url":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/1822W-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/ingegneria-meccanica\/orabond-1822-pe-schiuma-nastro-adesivo\/","url":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/ingegneria-meccanica\/orabond-1822-pe-schiuma-nastro-adesivo\/","name":"ORABOND\u00ae 1822 Nastro adesivo in schiuma PE | Cardinal TAPES","isPartOf":{"@id":"https:\/\/cardinal-tapes.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/ingegneria-meccanica\/orabond-1822-pe-schiuma-nastro-adesivo\/#primaryimage"},"image":{"@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/ingegneria-meccanica\/orabond-1822-pe-schiuma-nastro-adesivo\/#primaryimage"},"thumbnailUrl":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/1822W-scaled.jpg","datePublished":"2023-06-05T14:47:05+00:00","description":"Orabond 1822 \u00e8 costituito da una schiuma di polietilene nera a cellule chiuse rivestita su entrambi i lati con un adesivo acrilico sensibile alla pressione.","breadcrumb":{"@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/ingegneria-meccanica\/orabond-1822-pe-schiuma-nastro-adesivo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/ingegneria-meccanica\/orabond-1822-pe-schiuma-nastro-adesivo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/ingegneria-meccanica\/orabond-1822-pe-schiuma-nastro-adesivo\/#primaryimage","url":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/1822W-scaled.jpg","contentUrl":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/1822W-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi\/ingegneria-meccanica\/orabond-1822-pe-schiuma-nastro-adesivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cardinal-tapes.com\/it\/casa\/"},{"@type":"ListItem","position":2,"name":"Nastri adesivi","item":"https:\/\/cardinal-tapes.com\/it\/nastri-adesivi-it\/"},{"@type":"ListItem","position":3,"name":"Ingegneria meccanica","item":"https:\/\/cardinal-tapes.com\/it\/categoria\/ingegneria-meccanica\/"},{"@type":"ListItem","position":4,"name":"ORABOND\u00ae 1822 Nastro adesivo in schiuma PE"}]},{"@type":"WebSite","@id":"https:\/\/cardinal-tapes.com\/#website","url":"https:\/\/cardinal-tapes.com\/","name":"cardinal TAPES","description":"Klebetechnik aus Wuppertal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cardinal-tapes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"brands":[{"id":2802,"name":"ORAFOL","slug":"orafol-it"}],"_links":{"self":[{"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/product\/38411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/media\/29241"}],"wp:attachment":[{"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/media?parent=38411"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/pwb-brand?post=38411"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/product_brand?post=38411"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/product_cat?post=38411"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/it\/wp-json\/wp\/v2\/product_tag?post=38411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}