{"id":60457,"date":"2017-12-22T09:34:04","date_gmt":"2023-06-06T08:05:34","guid":{"rendered":"https:\/\/cardinal.pixel-tal.de\/klebebaender\/sin%20categor\u00eda\/3m-dp-807-adhesivo-bicomponente-de-base-acrilica-para-la-construccion\/"},"modified":"2023-06-06T10:23:04","modified_gmt":"2023-06-06T08:23:04","slug":"3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato","status":"publish","type":"product","link":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/adhesivos-liquidos\/adhesivos\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\/","title":{"rendered":"3M\u2122 DP 807 Adhesivo bicomponente de base acr\u00edlica para la construcci\u00f3n."},"content":{"rendered":"<p>El adhesivo de construcci\u00f3n de base acr\u00edlica de dos componentes 3M\u2122 DP 807 es especialmente resistente al pelado y puede aplicarse f\u00e1cilmente y en el menor tiempo posible. Los \u00e1mbitos de aplicaci\u00f3n del adhesivo son principalmente la uni\u00f3n de metales, pl\u00e1sticos y muchos otros materiales. La ventaja es que el producto se cura a temperatura ambiente.<\/p>","protected":false},"excerpt":{"rendered":"<p>El adhesivo de construcci\u00f3n de base acr\u00edlica de dos componentes 3M\u2122 DP 807 es especialmente resistente al pelado y puede aplicarse f\u00e1cilmente y en el menor tiempo posible. Los \u00e1mbitos de aplicaci\u00f3n del adhesivo son principalmente la uni\u00f3n de metales, pl\u00e1sticos y muchos otros materiales. La ventaja es que el producto se cura a temperatura &#8230; <a title=\"3M\u2122 DP 807 Adhesivo bicomponente de base acr\u00edlica para la construcci\u00f3n.\" class=\"read-more\" href=\"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/adhesivos-liquidos\/adhesivos\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\/\" aria-label=\"Leer m\u00e1s sobre 3M\u2122 DP 807 Adhesivo bicomponente de base acr\u00edlica para la construcci\u00f3n.\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"featured_media":25591,"template":"","meta":{"_acf_changed":false},"pwb-brand":[2169],"product_brand":[],"product_cat":[1869],"product_tag":[],"class_list":["post-60457","product","type-product","status-publish","has-post-thumbnail","pwb-brand-3m-es","product_cat-adhesivos","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3M DP 807 Adhesivo acr\u00edlico bicomponente para la construcci\u00f3n<\/title>\n<meta name=\"description\" content=\"El adhesivo de construcci\u00f3n de dos componentes a base de acrilato 3M DP 807 es especialmente resistente al pelado y puede aplicarse f\u00e1cilmente y en muy poco tiempo. M\u00e1s informaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/adhesivos-liquidos\/adhesivos\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3M DP 807 Adhesivo acr\u00edlico bicomponente para la construcci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El adhesivo de construcci\u00f3n de dos componentes a base de acrilato 3M DP 807 es especialmente resistente al pelado y puede aplicarse f\u00e1cilmente y en muy poco tiempo. M\u00e1s informaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/adhesivos-liquidos\/adhesivos\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\/\" \/>\n<meta property=\"og:site_name\" content=\"cardinal Tapes\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-06T08:23:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/3m_zk-konstruktionsklebestoff_dp807.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/adhesivos-liquidos\\\/adhesivos\\\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\\\/\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/adhesivos-liquidos\\\/adhesivos\\\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\\\/\",\"name\":\"3M DP 807 Adhesivo acr\u00edlico bicomponente para la construcci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/adhesivos-liquidos\\\/adhesivos\\\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/adhesivos-liquidos\\\/adhesivos\\\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/3m_zk-konstruktionsklebestoff_dp807.jpg\",\"datePublished\":\"2023-06-06T08:05:34+00:00\",\"dateModified\":\"2023-06-06T08:23:04+00:00\",\"description\":\"El adhesivo de construcci\u00f3n de dos componentes a base de acrilato 3M DP 807 es especialmente resistente al pelado y puede aplicarse f\u00e1cilmente y en muy poco tiempo. M\u00e1s informaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/adhesivos-liquidos\\\/adhesivos\\\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/adhesivos-liquidos\\\/adhesivos\\\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/adhesivos-liquidos\\\/adhesivos\\\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/3m_zk-konstruktionsklebestoff_dp807.jpg\",\"contentUrl\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/3m_zk-konstruktionsklebestoff_dp807.jpg\",\"width\":600,\"height\":600,\"caption\":\"3M Adhesivo de construcci\u00f3n DP807\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/adhesivos-liquidos\\\/adhesivos\\\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todos los productos\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adhesivos l\u00edquidos\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/categora\\\/adhesivos-liquidos\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Adhesivos\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/categora\\\/adhesivos-liquidos\\\/adhesivos\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"3M\u2122 DP 807 Adhesivo bicomponente de base acr\u00edlica para la construcci\u00f3n.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/\",\"name\":\"cardinal TAPES\",\"description\":\"Klebetechnik aus Wuppertal\",\"publisher\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/#organization\",\"name\":\"Cardinal Tapes\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/cardinal-tapes-logo.svg\",\"contentUrl\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/cardinal-tapes-logo.svg\",\"width\":216,\"height\":56,\"caption\":\"Cardinal Tapes\"},\"image\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3M DP 807 Adhesivo acr\u00edlico bicomponente para la construcci\u00f3n","description":"El adhesivo de construcci\u00f3n de dos componentes a base de acrilato 3M DP 807 es especialmente resistente al pelado y puede aplicarse f\u00e1cilmente y en muy poco tiempo. M\u00e1s informaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/adhesivos-liquidos\/adhesivos\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\/","og_locale":"es_ES","og_type":"article","og_title":"3M DP 807 Adhesivo acr\u00edlico bicomponente para la construcci\u00f3n","og_description":"El adhesivo de construcci\u00f3n de dos componentes a base de acrilato 3M DP 807 es especialmente resistente al pelado y puede aplicarse f\u00e1cilmente y en muy poco tiempo. M\u00e1s informaci\u00f3n.","og_url":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/adhesivos-liquidos\/adhesivos\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\/","og_site_name":"cardinal Tapes","article_modified_time":"2023-06-06T08:23:04+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/3m_zk-konstruktionsklebestoff_dp807.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/adhesivos-liquidos\/adhesivos\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\/","url":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/adhesivos-liquidos\/adhesivos\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\/","name":"3M DP 807 Adhesivo acr\u00edlico bicomponente para la construcci\u00f3n","isPartOf":{"@id":"https:\/\/cardinal-tapes.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/adhesivos-liquidos\/adhesivos\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\/#primaryimage"},"image":{"@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/adhesivos-liquidos\/adhesivos\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\/#primaryimage"},"thumbnailUrl":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/3m_zk-konstruktionsklebestoff_dp807.jpg","datePublished":"2023-06-06T08:05:34+00:00","dateModified":"2023-06-06T08:23:04+00:00","description":"El adhesivo de construcci\u00f3n de dos componentes a base de acrilato 3M DP 807 es especialmente resistente al pelado y puede aplicarse f\u00e1cilmente y en muy poco tiempo. M\u00e1s informaci\u00f3n.","breadcrumb":{"@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/adhesivos-liquidos\/adhesivos\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/adhesivos-liquidos\/adhesivos\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/adhesivos-liquidos\/adhesivos\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\/#primaryimage","url":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/3m_zk-konstruktionsklebestoff_dp807.jpg","contentUrl":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/3m_zk-konstruktionsklebestoff_dp807.jpg","width":600,"height":600,"caption":"3M Adhesivo de construcci\u00f3n DP807"},{"@type":"BreadcrumbList","@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/adhesivos-liquidos\/adhesivos\/3m-dp-807-adhesivo-de-construccion-de-dos-componentes-a-base-de-acrilato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cardinal-tapes.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"Todos los productos","item":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/"},{"@type":"ListItem","position":3,"name":"Adhesivos l\u00edquidos","item":"https:\/\/cardinal-tapes.com\/es\/categora\/adhesivos-liquidos\/"},{"@type":"ListItem","position":4,"name":"Adhesivos","item":"https:\/\/cardinal-tapes.com\/es\/categora\/adhesivos-liquidos\/adhesivos\/"},{"@type":"ListItem","position":5,"name":"3M\u2122 DP 807 Adhesivo bicomponente de base acr\u00edlica para la construcci\u00f3n."}]},{"@type":"WebSite","@id":"https:\/\/cardinal-tapes.com\/es\/#website","url":"https:\/\/cardinal-tapes.com\/es\/","name":"cardinal TAPES","description":"Klebetechnik aus Wuppertal","publisher":{"@id":"https:\/\/cardinal-tapes.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cardinal-tapes.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cardinal-tapes.com\/es\/#organization","name":"Cardinal Tapes","url":"https:\/\/cardinal-tapes.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cardinal-tapes.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/cardinal-tapes-logo.svg","contentUrl":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/cardinal-tapes-logo.svg","width":216,"height":56,"caption":"Cardinal Tapes"},"image":{"@id":"https:\/\/cardinal-tapes.com\/es\/#\/schema\/logo\/image\/"}}]}},"brands":[{"id":2169,"name":"3M","slug":"3m-es"}],"_links":{"self":[{"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/product\/60457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/media\/25591"}],"wp:attachment":[{"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/media?parent=60457"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/pwb-brand?post=60457"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/product_brand?post=60457"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/product_cat?post=60457"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/product_tag?post=60457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}