{"id":56480,"date":"2018-02-21T07:43:42","date_gmt":"2023-06-05T15:25:40","guid":{"rendered":"https:\/\/cardinal.pixel-tal.de\/klebebaender\/sin%20categor\u00eda\/ca-14-cinta-de-pintor\/"},"modified":"2025-07-03T10:08:16","modified_gmt":"2025-07-03T08:08:16","slug":"ca-14-cinta-de-pintor","status":"publish","type":"product","link":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/ambitos-de-aplicacion\/industria-del-automovil\/ca-14-cinta-de-pintor\/","title":{"rendered":"CA-14 Cinta de pintor"},"content":{"rendered":"<p>CA-14 Coating Masking Tape es una cinta de papel ligeramente crepada que tiene una buena fuerza adhesiva. Esto garantiza una adherencia r\u00e1pida y elevada incluso sobre caucho, vidrio y otras superficies.<\/p>\n<p>El soporte es extremadamente flexible, permite una uni\u00f3n precisa en tramos rectos largos, as\u00ed como en curvas dif\u00edciles, y favorece unos resultados de pintura limpios con bordes de pintura afilados y precisos. CA-14 se caracteriza adem\u00e1s porque puede utilizarse durante un periodo m\u00e1ximo de tiempo. 4 d\u00edas puede utilizarse en el exterior sin dejar restos de adhesivo. Incluso despu\u00e9s de secarse, la cinta suele ser f\u00e1cil de despegar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CA-14 Coating Masking Tape es una cinta de papel ligeramente crepada que tiene una buena fuerza adhesiva. Esto garantiza una adherencia r\u00e1pida y elevada incluso sobre caucho, vidrio y otras superficies. El soporte es extremadamente flexible, permite una uni\u00f3n precisa en tramos rectos largos, as\u00ed como en curvas dif\u00edciles, y favorece unos resultados de pintura [&hellip;]<\/p>\n","protected":false},"featured_media":26959,"template":"","meta":{"_acf_changed":false},"pwb-brand":[2175],"product_brand":[],"product_cat":[1697,1709,1711,1796,1806],"product_tag":[],"class_list":["post-56480","product","type-product","status-publish","has-post-thumbnail","pwb-brand-cardinal-gmbh-es","product_cat-industria-del-automovil","product_cat-cinta-de-pintor","product_cat-ingenieria-mecanica","product_cat-cinta-de-papel","product_cat-cintas-adhesivas-de-una-cara","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CA-14 Cinta de pintor | CINTAS Cardinal<\/title>\n<meta name=\"description\" content=\"CA-14 es una cinta de enmascarar para pintura que tiene una gran adherencia al caucho, el vidrio y otras superficies diversas. Obtenga m\u00e1s informaci\u00f3n aqu\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/ambitos-de-aplicacion\/industria-del-automovil\/ca-14-cinta-de-pintor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CA-14 Cinta de pintor | CINTAS Cardinal\" \/>\n<meta property=\"og:description\" content=\"CA-14 es una cinta de enmascarar para pintura que tiene una gran adherencia al caucho, el vidrio y otras superficies diversas. Obtenga m\u00e1s informaci\u00f3n aqu\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/ambitos-de-aplicacion\/industria-del-automovil\/ca-14-cinta-de-pintor\/\" \/>\n<meta property=\"og:site_name\" content=\"cardinal TAPES\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-03T08:08:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/CA_14.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/ambitos-de-aplicacion\\\/industria-del-automovil\\\/ca-14-cinta-de-pintor\\\/\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/ambitos-de-aplicacion\\\/industria-del-automovil\\\/ca-14-cinta-de-pintor\\\/\",\"name\":\"CA-14 Cinta de pintor | CINTAS Cardinal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/ambitos-de-aplicacion\\\/industria-del-automovil\\\/ca-14-cinta-de-pintor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/ambitos-de-aplicacion\\\/industria-del-automovil\\\/ca-14-cinta-de-pintor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/CA_14.jpg\",\"datePublished\":\"2023-06-05T15:25:40+00:00\",\"dateModified\":\"2025-07-03T08:08:16+00:00\",\"description\":\"CA-14 es una cinta de enmascarar para pintura que tiene una gran adherencia al caucho, el vidrio y otras superficies diversas. Obtenga m\u00e1s informaci\u00f3n aqu\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/ambitos-de-aplicacion\\\/industria-del-automovil\\\/ca-14-cinta-de-pintor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/ambitos-de-aplicacion\\\/industria-del-automovil\\\/ca-14-cinta-de-pintor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/ambitos-de-aplicacion\\\/industria-del-automovil\\\/ca-14-cinta-de-pintor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/CA_14.jpg\",\"contentUrl\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/CA_14.jpg\",\"width\":1400,\"height\":1400,\"caption\":\"CA 14\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/ambitos-de-aplicacion\\\/industria-del-automovil\\\/ca-14-cinta-de-pintor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cintas adhesivas\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c1mbitos de aplicaci\u00f3n\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/categora\\\/ambitos-de-aplicacion\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Industria del autom\u00f3vil\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/categora\\\/industria-del-automovil\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"CA-14 Cinta de pintor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/#website\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/\",\"name\":\"cardinal TAPES\",\"description\":\"Klebetechnik aus Wuppertal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cardinal-tapes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CA-14 Cinta de pintor | CINTAS Cardinal","description":"CA-14 es una cinta de enmascarar para pintura que tiene una gran adherencia al caucho, el vidrio y otras superficies diversas. Obtenga m\u00e1s informaci\u00f3n aqu\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/ambitos-de-aplicacion\/industria-del-automovil\/ca-14-cinta-de-pintor\/","og_locale":"es_ES","og_type":"article","og_title":"CA-14 Cinta de pintor | CINTAS Cardinal","og_description":"CA-14 es una cinta de enmascarar para pintura que tiene una gran adherencia al caucho, el vidrio y otras superficies diversas. Obtenga m\u00e1s informaci\u00f3n aqu\u00ed.","og_url":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/ambitos-de-aplicacion\/industria-del-automovil\/ca-14-cinta-de-pintor\/","og_site_name":"cardinal TAPES","article_modified_time":"2025-07-03T08:08:16+00:00","og_image":[{"width":1400,"height":1400,"url":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/CA_14.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/ambitos-de-aplicacion\/industria-del-automovil\/ca-14-cinta-de-pintor\/","url":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/ambitos-de-aplicacion\/industria-del-automovil\/ca-14-cinta-de-pintor\/","name":"CA-14 Cinta de pintor | CINTAS Cardinal","isPartOf":{"@id":"https:\/\/cardinal-tapes.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/ambitos-de-aplicacion\/industria-del-automovil\/ca-14-cinta-de-pintor\/#primaryimage"},"image":{"@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/ambitos-de-aplicacion\/industria-del-automovil\/ca-14-cinta-de-pintor\/#primaryimage"},"thumbnailUrl":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/CA_14.jpg","datePublished":"2023-06-05T15:25:40+00:00","dateModified":"2025-07-03T08:08:16+00:00","description":"CA-14 es una cinta de enmascarar para pintura que tiene una gran adherencia al caucho, el vidrio y otras superficies diversas. Obtenga m\u00e1s informaci\u00f3n aqu\u00ed.","breadcrumb":{"@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/ambitos-de-aplicacion\/industria-del-automovil\/ca-14-cinta-de-pintor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/ambitos-de-aplicacion\/industria-del-automovil\/ca-14-cinta-de-pintor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/ambitos-de-aplicacion\/industria-del-automovil\/ca-14-cinta-de-pintor\/#primaryimage","url":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/CA_14.jpg","contentUrl":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/CA_14.jpg","width":1400,"height":1400,"caption":"CA 14"},{"@type":"BreadcrumbList","@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/ambitos-de-aplicacion\/industria-del-automovil\/ca-14-cinta-de-pintor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cardinal-tapes.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cintas adhesivas","item":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas-es\/"},{"@type":"ListItem","position":3,"name":"\u00c1mbitos de aplicaci\u00f3n","item":"https:\/\/cardinal-tapes.com\/es\/categora\/ambitos-de-aplicacion\/"},{"@type":"ListItem","position":4,"name":"Industria del autom\u00f3vil","item":"https:\/\/cardinal-tapes.com\/es\/categora\/industria-del-automovil\/"},{"@type":"ListItem","position":5,"name":"CA-14 Cinta de pintor"}]},{"@type":"WebSite","@id":"https:\/\/cardinal-tapes.com\/#website","url":"https:\/\/cardinal-tapes.com\/","name":"cardinal TAPES","description":"Klebetechnik aus Wuppertal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cardinal-tapes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"brands":[{"id":2175,"name":"cardinal GmbH","slug":"cardinal-gmbh-es"}],"_links":{"self":[{"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/product\/56480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/media\/26959"}],"wp:attachment":[{"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/media?parent=56480"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/pwb-brand?post=56480"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/product_brand?post=56480"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/product_cat?post=56480"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/product_tag?post=56480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}