{"id":47744,"date":"2018-05-02T10:07:17","date_gmt":"2018-05-02T08:07:17","guid":{"rendered":"https:\/\/cardinal.pixel-tal.de\/klebebaender\/sin%20categor\u00eda\/ca-722-pelicula-pet-metalizada\/"},"modified":"2025-07-02T14:35:53","modified_gmt":"2025-07-02T12:35:53","slug":"ca-722-hoja-metalizada-para-mascotas","status":"publish","type":"product","link":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/cintas-adhesivas-de-una-cara\/cinta-pet\/ca-722-hoja-metalizada-para-mascotas\/","title":{"rendered":"CA-722 Pel\u00edcula PET metalizada"},"content":{"rendered":"<p>CA-722 es una pel\u00edcula metalizada de PET recubierta con un adhesivo acr\u00edlico resistente a los disolventes.<br \/>\nEl producto es adecuado para enmascarar en zonas donde se requiere resistencia t\u00e9rmica y qu\u00edmica. El producto tambi\u00e9n se utiliza para aplicaciones de empalme y es ideal para la detecci\u00f3n de metales en procesos automatizados. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>CA-722 es una pel\u00edcula metalizada de PET recubierta con un adhesivo acr\u00edlico resistente a los disolventes. El producto es adecuado para enmascarar en zonas donde se requiere resistencia t\u00e9rmica y qu\u00edmica. El producto tambi\u00e9n se utiliza para aplicaciones de empalme y es ideal para la detecci\u00f3n de metales en procesos automatizados.<\/p>\n","protected":false},"featured_media":26907,"template":"","meta":{"_acf_changed":false},"pwb-brand":[2175],"product_brand":[],"product_cat":[1806,1809],"product_tag":[],"class_list":["post-47744","product","type-product","status-publish","has-post-thumbnail","pwb-brand-cardinal-gmbh-es","product_cat-cintas-adhesivas-de-una-cara","product_cat-cinta-pet","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CA-722 Film PET metalizado | Cardinal TAPES<\/title>\n<meta name=\"description\" content=\"CA-722 es una pel\u00edcula de PET metalizado recubierta con un adhesivo acr\u00edlico resistente a los disolventes, por ejemplo para aplicaciones de empalme.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/cintas-adhesivas-de-una-cara\/cinta-pet\/ca-722-hoja-metalizada-para-mascotas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CA-722 Film PET metalizado | Cardinal TAPES\" \/>\n<meta property=\"og:description\" content=\"CA-722 es una pel\u00edcula de PET metalizado recubierta con un adhesivo acr\u00edlico resistente a los disolventes, por ejemplo para aplicaciones de empalme.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/cintas-adhesivas-de-una-cara\/cinta-pet\/ca-722-hoja-metalizada-para-mascotas\/\" \/>\n<meta property=\"og:site_name\" content=\"cardinal TAPES\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-02T12:35:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/CA_721_02-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/cintas-adhesivas-de-una-cara\\\/cinta-pet\\\/ca-722-hoja-metalizada-para-mascotas\\\/\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/cintas-adhesivas-de-una-cara\\\/cinta-pet\\\/ca-722-hoja-metalizada-para-mascotas\\\/\",\"name\":\"CA-722 Film PET metalizado | Cardinal TAPES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/cintas-adhesivas-de-una-cara\\\/cinta-pet\\\/ca-722-hoja-metalizada-para-mascotas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/cintas-adhesivas-de-una-cara\\\/cinta-pet\\\/ca-722-hoja-metalizada-para-mascotas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/CA_721_02-2.jpg\",\"datePublished\":\"2018-05-02T08:07:17+00:00\",\"dateModified\":\"2025-07-02T12:35:53+00:00\",\"description\":\"CA-722 es una pel\u00edcula de PET metalizado recubierta con un adhesivo acr\u00edlico resistente a los disolventes, por ejemplo para aplicaciones de empalme.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/cintas-adhesivas-de-una-cara\\\/cinta-pet\\\/ca-722-hoja-metalizada-para-mascotas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/cintas-adhesivas-de-una-cara\\\/cinta-pet\\\/ca-722-hoja-metalizada-para-mascotas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/cintas-adhesivas-de-una-cara\\\/cinta-pet\\\/ca-722-hoja-metalizada-para-mascotas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/CA_721_02-2.jpg\",\"contentUrl\":\"https:\\\/\\\/cardinal-tapes.com\\\/wp-content\\\/uploads\\\/CA_721_02-2.jpg\",\"width\":1400,\"height\":1400,\"caption\":\"CA_721\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas\\\/cintas-adhesivas-de-una-cara\\\/cinta-pet\\\/ca-722-hoja-metalizada-para-mascotas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cintas adhesivas\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/es\\\/cintas-adhesivas-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Einseitige Klebeb\u00e4nder\",\"item\":\"https:\\\/\\\/cardinal-tapes.com\\\/kategorie\\\/einseitige-klebebaender\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"CA-722 Pel\u00edcula PET metalizada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cardinal-tapes.com\\\/#website\",\"url\":\"https:\\\/\\\/cardinal-tapes.com\\\/\",\"name\":\"cardinal TAPES\",\"description\":\"Klebetechnik aus Wuppertal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cardinal-tapes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CA-722 Film PET metalizado | Cardinal TAPES","description":"CA-722 es una pel\u00edcula de PET metalizado recubierta con un adhesivo acr\u00edlico resistente a los disolventes, por ejemplo para aplicaciones de empalme.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/cintas-adhesivas-de-una-cara\/cinta-pet\/ca-722-hoja-metalizada-para-mascotas\/","og_locale":"es_ES","og_type":"article","og_title":"CA-722 Film PET metalizado | Cardinal TAPES","og_description":"CA-722 es una pel\u00edcula de PET metalizado recubierta con un adhesivo acr\u00edlico resistente a los disolventes, por ejemplo para aplicaciones de empalme.","og_url":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/cintas-adhesivas-de-una-cara\/cinta-pet\/ca-722-hoja-metalizada-para-mascotas\/","og_site_name":"cardinal TAPES","article_modified_time":"2025-07-02T12:35:53+00:00","og_image":[{"width":1400,"height":1400,"url":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/CA_721_02-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/cintas-adhesivas-de-una-cara\/cinta-pet\/ca-722-hoja-metalizada-para-mascotas\/","url":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/cintas-adhesivas-de-una-cara\/cinta-pet\/ca-722-hoja-metalizada-para-mascotas\/","name":"CA-722 Film PET metalizado | Cardinal TAPES","isPartOf":{"@id":"https:\/\/cardinal-tapes.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/cintas-adhesivas-de-una-cara\/cinta-pet\/ca-722-hoja-metalizada-para-mascotas\/#primaryimage"},"image":{"@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/cintas-adhesivas-de-una-cara\/cinta-pet\/ca-722-hoja-metalizada-para-mascotas\/#primaryimage"},"thumbnailUrl":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/CA_721_02-2.jpg","datePublished":"2018-05-02T08:07:17+00:00","dateModified":"2025-07-02T12:35:53+00:00","description":"CA-722 es una pel\u00edcula de PET metalizado recubierta con un adhesivo acr\u00edlico resistente a los disolventes, por ejemplo para aplicaciones de empalme.","breadcrumb":{"@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/cintas-adhesivas-de-una-cara\/cinta-pet\/ca-722-hoja-metalizada-para-mascotas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/cintas-adhesivas-de-una-cara\/cinta-pet\/ca-722-hoja-metalizada-para-mascotas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/cintas-adhesivas-de-una-cara\/cinta-pet\/ca-722-hoja-metalizada-para-mascotas\/#primaryimage","url":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/CA_721_02-2.jpg","contentUrl":"https:\/\/cardinal-tapes.com\/wp-content\/uploads\/CA_721_02-2.jpg","width":1400,"height":1400,"caption":"CA_721"},{"@type":"BreadcrumbList","@id":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas\/cintas-adhesivas-de-una-cara\/cinta-pet\/ca-722-hoja-metalizada-para-mascotas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cardinal-tapes.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cintas adhesivas","item":"https:\/\/cardinal-tapes.com\/es\/cintas-adhesivas-es\/"},{"@type":"ListItem","position":3,"name":"Einseitige Klebeb\u00e4nder","item":"https:\/\/cardinal-tapes.com\/kategorie\/einseitige-klebebaender\/"},{"@type":"ListItem","position":4,"name":"CA-722 Pel\u00edcula PET metalizada"}]},{"@type":"WebSite","@id":"https:\/\/cardinal-tapes.com\/#website","url":"https:\/\/cardinal-tapes.com\/","name":"cardinal TAPES","description":"Klebetechnik aus Wuppertal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cardinal-tapes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"brands":[{"id":2175,"name":"cardinal GmbH","slug":"cardinal-gmbh-es"}],"_links":{"self":[{"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/product\/47744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/media\/26907"}],"wp:attachment":[{"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/media?parent=47744"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/pwb-brand?post=47744"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/product_brand?post=47744"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/product_cat?post=47744"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cardinal-tapes.com\/es\/wp-json\/wp\/v2\/product_tag?post=47744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}